{"id":1495,"date":"2021-12-17T13:37:55","date_gmt":"2021-12-17T06:37:55","guid":{"rendered":"https:\/\/www.suksapunkalasin.net\/book\/product\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%af-%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%9a%e0%b8%97%e0%b8%a1%e0%b8%b2%e0%b8%95%e0%b8%a3%e0%b8%90%e0%b8%b2%e0%b8%99-%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7-5\/"},"modified":"2021-12-17T13:38:00","modified_gmt":"2021-12-17T06:38:00","slug":"%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%af-%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%9a%e0%b8%97%e0%b8%a1%e0%b8%b2%e0%b8%95%e0%b8%a3%e0%b8%90%e0%b8%b2%e0%b8%99-%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7-5","status":"publish","type":"product","link":"https:\/\/www.suksapunkalasin.net\/book\/product\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%af-%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%9a%e0%b8%97%e0%b8%a1%e0%b8%b2%e0%b8%95%e0%b8%a3%e0%b8%90%e0%b8%b2%e0%b8%99-%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7-5\/","title":{"rendered":"\u0e2a\u0e37\u0e48\u0e2d\u0e2f \u0e41\u0e21\u0e48\u0e1a\u0e17\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e14\u0e19\u0e15\u0e23\u0e35 &#8211; \u0e19\u0e32\u0e0f\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e1b.4 (\u0e2d\u0e08\u0e17)"},"content":{"rendered":"<p>\u0e2a\u0e37\u0e48\u0e2d\u0e2f \u0e41\u0e21\u0e48\u0e1a\u0e17\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e14\u0e19\u0e15\u0e23\u0e35 &#8211; \u0e19\u0e32\u0e0f\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e1b.4 (\u0e2d\u0e08\u0e17)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e37\u0e48\u0e2d\u0e2f \u0e41\u0e21\u0e48\u0e1a\u0e17\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e14\u0e19\u0e15\u0e23\u0e35 &#8211; \u0e19\u0e32\u0e0f\u0e28\u0e34\u0e25\u0e1b [&#8230;]\n","protected":false},"featured_media":1496,"template":"","meta":[],"product_cat":[34,25],"product_tag":[],"class_list":["post-1495","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-34","product_cat--aksorn"],"_links":{"self":[{"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/product\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/media\/1496"}],"wp:attachment":[{"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/product_cat?post=1495"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.suksapunkalasin.net\/book\/wp-json\/wp\/v2\/product_tag?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}